{"id":34505,"date":"2020-06-08T17:30:12","date_gmt":"2020-06-08T15:30:12","guid":{"rendered":"https:\/\/frank-lovisolo.fr\/WordPress\/?p=34505"},"modified":"2026-01-26T08:00:06","modified_gmt":"2026-01-26T07:00:06","slug":"22-paysages-metempiriques","status":"publish","type":"post","link":"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/","title":{"rendered":"Vingt-deux Paysages M\u00e9tempiriques"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><div><span style=\"color: #ffffff; font-size: 4px;\">M\u00e9tempiriques M\u00e9tempiriques M\u00e9tempiriques M\u00e9tempiriques M\u00e9tempiriques M\u00e9tempiriques &#8211; Art num\u00e9rique &#8211;<\/span><\/div>\n<table style=\"width: 100%;\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td style=\"width: 40%; text-align: right; vertical-align: middle;\" colspan=\"3\">\n<div style=\"text-align: center;\"><strong><span style=\"font-size: 16px;\"><span style=\"font-size: 14px;\">Suggestion d&rsquo;\u00e9coute :<\/span><br \/>\n<a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/le-periple-de-demeter\/\">Le P\u00e9riple de D\u00e9m\u00e9ter<\/a><br \/>\n<\/span><\/strong><\/div>\n<\/td>\n<td style=\"width: 40%; text-align: right; vertical-align: middle;\">\n<div><a href=\"https:\/\/frankcesarlovisolo.bandcamp.com\/track\/le-p-riple-de-d-m-ter\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-51127\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2022\/11\/bandcamp-logotype-color-400-Frank.png\" alt=\"\" width=\"303\" height=\"25\" title=\"-\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2022\/11\/bandcamp-logotype-color-400-Frank.png 400w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2022\/11\/bandcamp-logotype-color-400-Frank-250x21.png 250w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2022\/11\/bandcamp-logotype-color-400-Frank-150x12.png 150w\" sizes=\"auto, (max-width: 303px) 100vw, 303px\" \/><\/a><\/div>\n<\/td>\n<td style=\"width: 20%; text-align: left; vertical-align: middle;\"><a href=\"#com\"><span style=\"font-size: 20px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15068\" title=\"Osmophore - darwin - \u00e9volution - lovisolo\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/06\/ComRouge.jpg\" alt=\"Frank-Cesar-Lovisolo\" width=\"250\" height=\"20\" \/><\/span><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div><\/div>\n<p><span style=\"color: #ffffff;\">&#8211;<\/span><\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">\n<div style=\"text-align: center;\"><span style=\"font-size: 20px;\">Il y en avait sept&#8230; D\u00e9sormais, il y en a vingt-deux, <i>vingt dieux !\u00a0<\/i><\/span><\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: 20px;\">Les anciens et les nouveaux paysages bariol\u00e9s, bigarr\u00e9s, chamar\u00e9s et composites.<\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: center;\"><div class=\"flagallerywraper\" style=\"text-align:center;\"><div class=\"flagallery flaslider_skin\" id=\"FlaGallery_sc1_285\" style=\"width:1024px;margin:0 auto;\"><script type=\"text\/javascript\">(function(){this['FlaGallery_sc1_285']={'settings':{\"sliderHeightRetio\":\"0.8\",\"sliderPreloaderColor\":\"#ffffff\",\"sliderBgColor\":\"rgb(255, 255, 255)\",\"sliderHeaderFooterBgColor\":\"rgb(255, 255, 255)\",\"sliderNavigationColor\":\"rgba(82, 82, 82, 0.81)\",\"sliderNavigationIconColor\":\"rgb(255, 255, 255)\",\"sliderItemDescriptionBlock\":\"0\",\"sliderItemTitleFontSize\":\"14\",\"sliderItemTitleTextColor\":\"#515151\",\"sliderItemDescriptionFontSize\":\"14\",\"sliderItemDescriptionTextColor\":\"#545454\",\"sliderThumbBarEnable\":\"1\",\"sliderThumbBarHoverColor\":\"#ffffff\",\"sliderThumbSubMenuBackgroundColor\":\"rgb(255, 255, 255)\",\"sliderThumbSubMenuBackgroundColorOver\":\"rgba(255,255,255,1)\",\"sliderThumbSubMenuIconColor\":\"rgb(0, 0, 0)\",\"sliderThumbSubMenuIconHoverColor\":\"rgba(0,0,0,1)\",\"sliderPlayButton\":\"1\",\"sliderZoomButton\":\"1\",\"sliderFullScreen\":\"1\",\"sliderInfoEnable\":\"1\",\"sliderItemDownload\":\"0\",\"sliderSocialShareEnabled\":\"0\",\"sliderLikesEnabled\":\"0\",\"sliderSlideshowEneble\":\"1\",\"slideshowDelay\":\"8\",\"slideshowProgressBarColor\":\"rgb(0, 0, 0)\",\"slideshowProgressBarBGColor\":\"rgb(137, 176, 255)\",\"modaBgColor\":\"rgba(0,0,0,0.9)\",\"modalInfoBoxBgColor\":\"rgb(255, 255, 255)\",\"modalInfoBoxTitleTextColor\":\"#000000\",\"shareTitlePlaceHolder\":\"Share\",\"modalInfoBoxTextColor\":\"#333333\",\"infoBarExifEnable\":\"0\",\"infoBarCountersEnable\":\"0\",\"infoBarDateInfoEnable\":\"0\",\"customCSS\":\"\",\"key\":\"2b91304c71a96bd3dd001bdb3bf4a76f\",\"name\":\"GRANDPackPlus\",\"galleryID\":\"sc1_285\",\"post_url\":\"https:\\\/\\\/frank-lovisolo.fr\\\/WordPress\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/34505\",\"module_url\":\"https:\\\/\\\/frank-lovisolo.fr\\\/WordPress\\\/wp-content\\\/plugins\\\/flagallery-skins\\\/flaslider\\\/\"}, 'data':[{\"gallery\":{\"gid\":\"285\",\"name\":\"22-paysages-metempiriques\",\"path\":\"https:\\\/\\\/frank-lovisolo.fr\\\/WordPress\\\/wp-content\\\/flagallery\\\/22-paysages-metempiriques\",\"title\":\"22 Paysages M\\u00e9tempiriques\",\"galdesc\":\"\"},\"data\":[{\"pid\":\"23585\",\"filename\":\"n001-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Le Ponton du Mourillon - Toulon\",\"alttext\":\"Le Ponton du Mourillon - Toulon\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"1186\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Le Ponton du Mourillon - Toulon\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Le Ponton du Mourillon - Toulon\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23586\",\"filename\":\"n002-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Le pont Charles \\u00e0 Pragues\",\"alttext\":\"Le pont Charles \\u00e0 Pragues\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"336\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Le pont Charles \\u00e0 Pragues\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":\"Lovisolo-Guillard Frank - 2020\",\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Le pont Charles \\u00e0 Pragues\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23587\",\"filename\":\"n003-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Pragues la ville\",\"alttext\":\"Pragues\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"218\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Pragues\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Pragues\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23588\",\"filename\":\"n004-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Venise\",\"alttext\":\"Venise\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"153\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Venise\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Venise\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23589\",\"filename\":\"n005-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Une vague devant le fort Saint Louis \\u00e0 Toulon\",\"alttext\":\"Une vague devant le fort Saint Louis \\u00e0 Toulon\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"125\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Une vague devant le fort Saint Louis \\u00e0 Toulon\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Une vague devant le fort Saint Louis \\u00e0 Toulon\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23590\",\"filename\":\"n006-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Toulon - Le port\",\"alttext\":\"Toulon - Le port\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"102\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Toulon - Le port\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Toulon - Le port\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23591\",\"filename\":\"n007-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Paestum - Le temple d'H\\u00e9ra\",\"alttext\":\"Paestum - Le temple d'H\\u00e9ra\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"98\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Paestum - Le temple d'H\\u00e9ra\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Paestum - Le temple d'H\\u00e9ra\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23592\",\"filename\":\"n008-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Il Duomo di Firenze\",\"alttext\":\"Il Duomo di Firenze\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"81\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Il Duomo di Firenze\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Il Duomo di Firenze\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23593\",\"filename\":\"n009-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Martigues\",\"alttext\":\"Martigues\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"71\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Martigues\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Martigues\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23594\",\"filename\":\"n010-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Pr\\u00e9s de la Mitre - Toulon\",\"alttext\":\"Pr\\u00e9s de la Mitre - Toulon\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"65\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Pr\\u00e9s de la Mitre - Toulon\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Pr\\u00e9s de la Mitre - Toulon\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23595\",\"filename\":\"n011-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"L'abre solitaire - Puyloubier\",\"alttext\":\"L'abre solitaire - Puyloubier\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"61\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"L'abre solitaire - Puyloubier\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"L'abre solitaire - Puyloubier\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23596\",\"filename\":\"n012-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Pomp\\u00e9i\",\"alttext\":\"Pomp\\u00e9i\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"53\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Pomp\\u00e9i\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Pomp\\u00e9i \",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23597\",\"filename\":\"n013-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Stazione ferroviaria di Milazzo - Sicilia\",\"alttext\":\"Stazione ferroviaria di Milazzo - Sicilia\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"48\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Stazione ferroviaria di Milazzo - Sicilia\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Stazione ferroviaria di Milazzo - Sicilia\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23598\",\"filename\":\"n014-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Un bulbe d'\\u00e9trave\",\"alttext\":\"Un bulbe d'\\u00e9trave\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"39\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Un bulbe d'\\u00e9trave\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Un bulbe d'\\u00e9trave\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23599\",\"filename\":\"n015-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Un chemin en Loz\\u00e8re\",\"alttext\":\"Un chemin en Loz\\u00e8re\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"39\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Un chemin en Loz\\u00e8re\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Un chemin en Loz\\u00e8re\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23600\",\"filename\":\"n016-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Saint-P\\u00e9tersbourg\",\"alttext\":\"Saint-P\\u00e9tersbourg\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"46\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Saint-P\\u00e9tersbourg\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Saint-P\\u00e9tersbourg\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23601\",\"filename\":\"n017-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Raffineria di Milazzo\",\"alttext\":\"Raffineria di Milazzo\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"36\",\"total_value\":\"0\",\"total_votes\":\"1\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Raffineria di Milazzo\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Raffineria di Milazzo\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23602\",\"filename\":\"n018-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Il Ponte Vecchio di Firenze\",\"alttext\":\"Il Ponte Vecchio di Firenze\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"40\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Il Ponte Vecchio di Firenze\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Il Ponte Vecchio di Firenze\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23603\",\"filename\":\"n019-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"La Grande Grue \\u00e0 la Seyne sur Mer\",\"alttext\":\"La Grande Grue \\u00e0 la Seyne sur Mer\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"41\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"La Grande Grue \\u00e0 la Seyne sur Mer\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"La Grande Grue \\u00e0 la Seyne sur Mer\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23604\",\"filename\":\"n020-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Une vague \\u00e0 Pors Loubous\",\"alttext\":\"Une vague \\u00e0 Pors Loubous\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"40\",\"total_value\":\"0\",\"total_votes\":\"0\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":\"Une vague \\u00e0 Pors Loubous\",\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":\"Une vague \\u00e0 Pors Loubous\",\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23605\",\"filename\":\"n021-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"Toulon - Voiliers\",\"alttext\":\"Toulon - Voiliers\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"35\",\"total_value\":\"0\",\"total_votes\":\"1\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":false,\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":false,\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}},{\"pid\":\"23606\",\"filename\":\"n022-paysage-metempirique-frank-lovisolo-2020.jpg\",\"description\":\"La Londe des Maures - Un coron minier sur la c\\u00f4te d'azur.\",\"alttext\":\"La Londe des Maures - Un coron minier sur la c\\u00f4te d'azur.\",\"link\":\"\",\"imagedate\":\"2012-02-12 12:37:40\",\"hitcounter\":\"42\",\"total_value\":\"0\",\"total_votes\":\"1\",\"meta_data\":{\"aperture\":\"F 3.3\",\"credit\":false,\"camera\":\"DMC-TZ5\",\"caption\":false,\"created_timestamp\":\"12 f\\u00e9vrier 2012 12 h 37 min\",\"copyright\":false,\"focal_length\":\"4.7min\",\"iso\":100,\"shutter_speed\":\"1\\\/400sec\",\"flash\":\"Not fired\",\"title\":false,\"keywords\":false,\"width\":1200,\"height\":849,\"saved\":true,\"thumbnail\":{\"width\":300,\"height\":212},\"webview\":{\"0\":1200,\"1\":849,\"2\":2,\"3\":\"width=\\\"1200\\\" height=\\\"849\\\"\",\"bits\":8,\"channels\":3,\"mime\":\"image\\\/jpeg\"}}}]}], };})();<\/script><\/div><\/div><noscript id=\"noscript_FlaGallery_sc1_285\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n001-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Le Ponton du Mourillon - Toulon\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n002-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Le pont Charles \u00e0 Pragues\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n003-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Pragues\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n004-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Venise\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n005-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Une vague devant le fort Saint Louis \u00e0 Toulon\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n006-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Toulon - Le port\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n007-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Paestum - Le temple d&#039;H\u00e9ra\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n008-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Il Duomo di Firenze\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n009-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Martigues\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n010-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Pr\u00e9s de la Mitre - Toulon\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n011-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"L&#039;abre solitaire - Puyloubier\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n012-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Pomp\u00e9i\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n013-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Stazione ferroviaria di Milazzo - Sicilia\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n014-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Un bulbe d&#039;\u00e9trave\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n015-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Un chemin en Loz\u00e8re\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n016-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Saint-P\u00e9tersbourg\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n017-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Raffineria di Milazzo\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n018-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Il Ponte Vecchio di Firenze\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n019-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"La Grande Grue \u00e0 la Seyne sur Mer\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n020-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Une vague \u00e0 Pors Loubous\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n021-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"Toulon - Voiliers\" title=\"-\"><img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy no-lazyload noLazy\" data-lazy-src=\"\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/flagallery\/22-paysages-metempiriques\/n022-paysage-metempirique-frank-lovisolo-2020.jpg\" alt=\"La Londe des Maures - Un coron minier sur la c\u00f4te d&#039;azur.\" title=\"-\"><\/noscript><\/p>\n<table style=\"width: 100%;\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td colspan=\"2\">\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"22-paysages-metempiriques-ou-la-couleur-nait-dune-olla-podrida-libertaire-et-numerique-la-suite-logique-ou-pas-des-7-premieres-images\"><\/span>22 paysages <a href=\"https:\/\/fr.wiktionary.org\/wiki\/m%C3%A9tempirique\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">m\u00e9tempiriques<\/a> o\u00f9 la couleur na\u00eet d\u2019une <a href=\"https:\/\/www.cnrtl.fr\/definition\/olla-podrida\" target=\"_blank\" rel=\"noopener noreferrer\">olla-podrida<\/a> libertaire et num\u00e9rique, la suite logique, ou pas, des <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/sept-paysages-metempiriques-num\/\" target=\"_blank\" rel=\"noopener noreferrer\">7 premi\u00e8res images<\/a>.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"color: #dadada;\">&#8211;<\/span><\/p>\n<div style=\"text-align: justify;\">\n<p><span style=\"font-size: 20px;\">La g\u00e9ographie, des murs \u00e9rod\u00e9s et color\u00e9s de lichens, supporte les photographies. Comme \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Prague\" target=\"_blank\" rel=\"noopener noreferrer\">Prague<\/a> une vue de la ville et le pont Charles (en tch\u00e8que : <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pont_Charles\" target=\"_blank\" rel=\"noopener noreferrer\">Karl\u016fv most<\/a>)\u00a0<\/em>et \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Toulon\" target=\"_blank\" rel=\"noopener noreferrer\">Toulon<\/a>, en structures maritimes au <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Mourillon\" target=\"_blank\" rel=\"noopener noreferrer\">Mourillon<\/a>. <\/span><\/p>\n<p><span style=\"font-size: 20px;\">Les nouvelles vous conduiront \u00e0 <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/tag\/venise\/\" target=\"_blank\" rel=\"noopener noreferrer\">Venise<\/a>, <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/paestum-le-plongeur-et-la-lumiere\/\" target=\"_blank\" rel=\"noopener noreferrer\">Paestum<\/a>, <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/florence-fleaux\/\" target=\"_blank\" rel=\"noopener noreferrer\">Florence<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Martigues\" target=\"_blank\" rel=\"noopener noreferrer\">Martigues<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Puyloubier\" target=\"_blank\" rel=\"noopener noreferrer\">Puyloubier<\/a>, <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/pline-herculanum-pompei\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pomp\u00e9i<\/a>, <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/stazione-ferroviaria-di-milazzo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Milazzo<\/a>, en <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/35-entre-cantal-et-lozere\/\" target=\"_blank\" rel=\"noopener noreferrer\">Loz\u00e8re<\/a>, <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/tag\/saint-petersbourg\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saint Petesbourg<\/a>, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/La_Seyne-sur-Mer\" target=\"_blank\" rel=\"noopener noreferrer\">La Seyne-sur-Mer,<\/a> <a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/neuf-vagues-pors-loubous\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pors Loubous<\/a> et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/La_Londe-les-Maures\" target=\"_blank\" rel=\"noopener noreferrer\">La Londe des Maures<\/a>&#8230;<\/span><\/p>\n<p><span style=\"font-size: 20px;\">Ainsi, la vision d\u2019un monde subjectif et un univers objectif se situe entre l\u2019imaginaire et la repr\u00e9sentation de ce que pourrait \u00eatre une irr\u00e9alit\u00e9 pr\u00e9textant la coloration. J\u2019esp\u00e8re avec ces 22 images une incertitude, une ind\u00e9termination et un doute qui provoqueront le chavirement d\u2019un paysage vers un lieu indiscernable.<\/span><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<div style=\"text-align: right;\"><span style=\"color: #65b2ff; font-size: 16px;\"><em><span style=\"background-color: #000032;\">\u00a0 \u00a0<\/span><\/em><a style=\"color: #65b2ff;\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/2\/\"><em><span style=\"background-color: #000032;\">Page suivante, <\/span><\/em><em><span style=\"background-color: #000032;\"> avec Diderot et L\u00e9onard de Vinci : deux causeries sur la peinture et la couleur<\/span><\/em><\/a><em><span style=\"background-color: #000032;\">&#8230;<\/span><\/em><\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<table style=\"width: 100%; border-collapse: collapse;\" cellpadding=\"10\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\">\n<p style=\"text-align: right;\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Denis_Diderot\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 32px;\">D<\/span>iderot<\/a>, 1766<span style=\"font-size: 32px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15971\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2013\/11\/DenisDiderot-560x695.jpg\" alt=\"Diderot - M\u00e9tempiriques\" width=\"190\" height=\"236\" title=\"-\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2013\/11\/DenisDiderot-560x695.jpg 560w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2013\/11\/DenisDiderot-121x150.jpg 121w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2013\/11\/DenisDiderot-150x186.jpg 150w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2013\/11\/DenisDiderot.jpg 930w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/span><\/p>\n<h3 style=\"text-align: right;\"><span class=\"ez-toc-section\" id=\"essais-sur-la-peinture\"><\/span><em>Essais sur la Peinture<\/em><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h4 style=\"text-align: right;\"><span class=\"ez-toc-section\" id=\"mes-petites-idees-sur-la-couleur\"><\/span><span style=\"text-decoration: underline;\">Mes petites id\u00e9es sur la couleur.<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">C\u2019est le dessin qui donne forme aux \u00eatres\u2009; c\u2019est la couleur qui leur donne la vie.<\/span><\/em><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Voil\u00e0 le souffle divin qui les anime. Il n\u2019y a que les ma\u00eetres dans l\u2019art qui soient bons juges du dessin, tout le monde peut juger de la couleur. On ne manque pas d\u2019excellents dessinateurs\u2009; il y a peu de grands coloristes.<\/span><\/em><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Il en est de m\u00eame en litt\u00e9rature\u00a0: cent froids logiciens pour un grand orateur\u2009; dix grands orateurs pour un po\u00e8te sublime. [\u00a0&#8230;\u00a0]<\/span><\/em><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">On a dit que la plus belle couleur qu\u2019il y eut au monde, \u00e9tait cette rougeur dont l\u2019innocence, la jeunesse, la sant\u00e9, la modestie et la pudeur coloraient les joues d\u2019une fille [\u00a0&#8230;\u00a0] c\u2019est ce m\u00e9lange de rouge et de bleu qui transpire insensiblement\u2009; c\u2019est le sang, la vie qui font le d\u00e9sespoir du coloriste. [\u00a0&#8230;\u00a0]<\/span><\/em><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Quel est donc, pour moi le vrai, le grand coloriste\u2009?<\/span><\/em><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">C\u2019est celui qui a pris le ton de la nature et des objets bien \u00e9clair\u00e9s, et qui a su accorder son tableau.<\/span><\/em><\/div>\n<div><em><span style=\"color: #ffffff;\">&#8211;<\/span><\/em><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><em><span style=\"font-size: 20px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-22242 size-full\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2019\/12\/leonard-de-vinci-autoportrait.jpg\" alt=\"\" width=\"190\" height=\"300\" title=\"-\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2019\/12\/leonard-de-vinci-autoportrait.jpg 190w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2019\/12\/leonard-de-vinci-autoportrait-95x150.jpg 95w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2019\/12\/leonard-de-vinci-autoportrait-150x237.jpg 150w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/span><\/em><span style=\"font-size: 20px;\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/L%C3%A9onard_de_Vinci\" target=\"_blank\" rel=\"noopener noreferrer\">L<\/a><\/span><em><span style=\"font-size: 20px;\">\u00e9onard de Vinci,<\/span><\/em><\/p>\n<h3><span class=\"ez-toc-section\" id=\"traite-de-la-peinture\"><\/span><span style=\"font-size: 20px;\">Trait\u00e9 de la Peinture<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div><em><span style=\"font-size: 20px;\">Chap 131<\/span><\/em><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Bien que le m\u00e9lange des couleurs l\u2019une avec l\u2019autre soit d\u2019une \u00e9tendue presque infinie, je ne laisserai pas pour cela d\u2019en toucher ici l\u00e9g\u00e8rement quelque chose.<\/span><\/em><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">\u00c9tablissant premi\u00e8rement un certain nombre de couleurs simples pour servir de fondement, et avec chacune d\u2019elles, m\u00ealant chacune des autres une \u00e0 une, puis deux \u00e0 deux, puis trois \u00e0 trois ; poursuivant ainsi jusques au m\u00e9lange entier de toutes les couleurs ensemble ; puis je recommencerai \u00e0 m\u00ealer ces couleurs deux \u00e0 deux, et trois \u00e0 trois, et puis quatre \u00e0 quatre, continuant ainsi jusqu\u2019\u00e0 la fin ; sur ce deux couleurs on en mettra trois [&#8230;] or, j\u2019appelle couleurs simples, celles qui ne sont point compos\u00e9es, et ne peuvent \u00eatre faites ni suppl\u00e9\u00e9es par aucun m\u00e9lange des autres couleurs.<\/span><\/em><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\n<p><em><span style=\"font-size: 20px;\">Le noir et le blanc ne sont point compt\u00e9es entre les couleurs, l\u2019un repr\u00e9sentant les t\u00e9n\u00e8bres, et l\u2019autre le jour; c\u2019est \u00e0 dire, l\u2019un \u00e9tant une simple privation de lumi\u00e8re, et l\u2019autre la lumi\u00e8re m\u00eame, ou primitive ou d\u00e9riv\u00e9e.\u00a0<\/span><\/em><\/p>\n<p><em><span style=\"font-size: 20px;\">Je ne laisserai cependant pas d\u2019en parler, parce que dans la Peinture il n\u2019y a rien de plus n\u00e9cessaire et qui soit plus d\u2019usage, toute la Peinture n\u2019\u00e9tant qu\u2019un effet et une composition des ombres et des lumi\u00e8res, c\u2019est \u00e0 dire de clair et d\u2019obscur.<\/span><\/em><\/p>\n<p><em><span style=\"font-size: 20px;\">Apr\u00e8s le noir et le blanc vient l\u2019azur, puis le vert ou le tann\u00e9, ou l\u2019ocre de terre d\u2019ombre, apr\u00e8s le pourpre ou le rouge, qui font en tout huit couleurs : comme il n\u2019y en a pas davantage dans la nature, je vais parler de leur m\u00e9lange. <\/span><\/em><\/p>\n<p><em><span style=\"font-size: 20px;\">Soient premi\u00e8rement m\u00eal\u00e9es ensemble le noir et le blanc, puis le noir et le jaune, et le noir et le rouge, ensuite le jaune et le noir, et le jaune et le rouge.<\/span><\/em><br \/>\n<em><span style=\"font-size: 20px;\">Chap. 84<\/span><\/em><br \/>\n<em><span style=\"font-size: 20px;\">Un corps qui renvoie la lumi\u00e8re sur un autre corps ne lui communique pas sa couleur telle qu\u2019il l\u2019a lui-m\u00eame ; mais il se fait un m\u00e9lange de plusieurs couleurs, s\u2019il y en a plusieurs qui soient port\u00e9es par des reflets dans un m\u00eame endroit [&#8230;].<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Chap 101<\/span><\/em><br \/>\n<em><span style=\"font-size: 20px;\">La teinte de l\u2019ombre, de quelque couleur que ce soit, participe toujours \u00e0 la couleur de son objet, et cela plus ou moins, selon qu\u2019il est ou plus proche ou plus \u00e9loign\u00e9 de l\u2019ombre, et \u00e0 proportion aussi de ce qu\u2019il y a plus ou moins de lumi\u00e8re (&#8230;).<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 20px;\">Chap 104<\/span><\/em><br \/>\n<em><span style=\"font-size: 20px;\">L\u2019ombre du blanc, \u00e9clair\u00e9 par le soleil et par l\u2019air, a sa teinte tirant sur le bleu, et cela vient de ce que le blanc de soi n\u2019est pas proprement une couleur, mais le sujet des autres couleurs [&#8230;].<\/span><\/em><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"text-align: center;\"><span style=\"color: #ffffff;\">&#8230;<\/span><a id=\"com\"><\/a><\/div>\n<h3><!--nextpage--><span style=\"font-size: 20px;\">Le terme m\u00e9tempirique<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18px;\">est surtout employ\u00e9 dans les courants issus du kantisme, de la ph\u00e9nom\u00e9nologie et de l\u2019\u00e9pist\u00e9mologie contemporaine. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18px;\">Il d\u00e9signe ce qui d\u00e9passe l\u2019exp\u00e9rience sensible sans en \u00eatre ind\u00e9pendant : des structures ou conditions qui rendent l\u2019exp\u00e9rience possible (formes a priori, cat\u00e9gories, structures de la conscience, cadres du savoir). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18px;\">On l\u2019utilise pr\u00e9cis\u00e9ment pour \u00e9viter une m\u00e9taphysique sp\u00e9culative tout en ne se limitant pas \u00e0 l\u2019empirisme.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18px;\">La diff\u00e9rence avec la m\u00e9taphysique est centrale : le m\u00e9tempirique ne cherche pas \u00e0 d\u00e9crire la r\u00e9alit\u00e9 en soi, mais les conditions de possibilit\u00e9 de notre exp\u00e9rience de la r\u00e9alit\u00e9. Il reste toujours li\u00e9 \u00e0 l\u2019exp\u00e9rience humaine, alors que la m\u00e9taphysique pr\u00e9tend souvent dire ce qui existe ind\u00e9pendamment de toute exp\u00e9rience. En ce sens, le m\u00e9tempirique est critique et m\u00e9thodologique, l\u00e0 o\u00f9 la m\u00e9taphysique est ontologique et sp\u00e9culative.<\/span><\/p>\n<p data-start=\"0\" data-end=\"42\"><span style=\"font-size: 20px;\"><strong data-start=\"0\" data-end=\"16\">M\u00e9tempirique<\/strong> <em data-start=\"17\" data-end=\"42\">(adjectif)<\/em><\/span><\/p>\n<p style=\"text-align: justify;\" data-start=\"44\" data-end=\"383\"><span style=\"font-size: 18px;\">Se dit de ce qui <strong data-start=\"61\" data-end=\"138\">d\u00e9passe le domaine de l\u2019exp\u00e9rience sensible et de l\u2019observation empirique<\/strong>, sans pour autant relever strictement de la m\u00e9taphysique classique. Le m\u00e9tempirique renvoie \u00e0 des <strong data-start=\"237\" data-end=\"276\">principes, structures ou conditions<\/strong> qui ne sont pas directement observables, mais qui <strong data-start=\"327\" data-end=\"382\">fondent, orientent ou rendent possible l\u2019exp\u00e9rience<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\" data-start=\"385\" data-end=\"399\"><span style=\"font-size: 18px;\">\u00a0En bref :<\/span><\/p>\n<div style=\"text-align: justify;\" data-start=\"402\" data-end=\"453\"><span style=\"font-size: 18px;\"><strong data-start=\"402\" data-end=\"415\">Empirique<\/strong> : fond\u00e9 sur l\u2019exp\u00e9rience observable<\/span><\/div>\n<div style=\"text-align: justify;\" data-start=\"456\" data-end=\"524\"><span style=\"font-size: 18px;\"><strong data-start=\"456\" data-end=\"472\">M\u00e9tempirique<\/strong> : au-del\u00e0 de l\u2019exp\u00e9rience, mais en lien avec elle<\/span><\/div>\n<div style=\"text-align: justify;\" data-start=\"527\" data-end=\"602\"><span style=\"font-size: 18px;\"><strong data-start=\"527\" data-end=\"543\">M\u00e9taphysique<\/strong> : au-del\u00e0 de l\u2019exp\u00e9rience et parfois ind\u00e9pendamment d\u2019elle<\/span><\/div>\n<p style=\"text-align: justify;\" data-start=\"604\" data-end=\"627\"><span style=\"font-size: 18px;\"><strong data-start=\"604\" data-end=\"625\">Exemple d\u2019usage :<\/strong><\/span><\/p>\n<blockquote data-start=\"628\" data-end=\"750\">\n<p data-start=\"630\" data-end=\"750\"><span style=\"font-size: 18px;\">\u00ab Les cat\u00e9gories de l\u2019entendement chez Kant peuvent \u00eatre comprises comme des structures m\u00e9tempiriques de l\u2019exp\u00e9rience. \u00bb<\/span><\/p>\n<\/blockquote>\n<div style=\"text-align: justify;\"><span style=\"color: #ffffff; font-size: 18px;\">&#8230;<\/span><a id=\"com\"><\/a><\/div>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a986b6524858\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a986b6524858\" checked \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/#22-paysages-metempiriques-ou-la-couleur-nait-dune-olla-podrida-libertaire-et-numerique-la-suite-logique-ou-pas-des-7-premieres-images\" >22 paysages m\u00e9tempiriques o\u00f9 la couleur na\u00eet d\u2019une olla-podrida libertaire et num\u00e9rique, la suite logique, ou pas, des 7 premi\u00e8res images.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/#essais-sur-la-peinture\" >Essais sur la Peinture<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/#mes-petites-idees-sur-la-couleur\" >Mes petites id\u00e9es sur la couleur.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/#traite-de-la-peinture\" >Trait\u00e9 de la Peinture<\/a><\/li><\/ul><\/nav><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 5<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Il y en avait sept&#8230; Dor\u00e9navant il y en a vingt-deux, vingt dieux\u00a0!\u00a0<br \/>\nLes nouvelles vous conduiront \u00e0 Venise, Paestum, Florence, Sanary-sur-Mer\u00a0, Puyloubier, Pomp\u00e9i, Milazzo, en Loz\u00e9re, Saint Petesbourg, La Seyne sur Mer, Pors Loubous et la londe des Maures&#8230;<br \/>\n <a class=\"continue-reading-link\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/22-paysages-metempiriques\/\">Suite &#8211; Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":39874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_ogeeat_og_title":"","_ogeeat_og_description":"","_ogeeat_og_image":"","_ogeeat_tw_title":"","_ogeeat_tw_description":"","_ogeeat_tw_image":"","footnotes":""},"categories":[2084,1,39,16],"tags":[2552,921,1248,3407,2079,2119,2080,2923,1613,2928,499,2925,2927,2924,479,1533],"class_list":["post-34505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-libertaire","category-tous-les-articles","category-art-contemporain","category-photographies","tag-art-numerique","tag-florence","tag-la-seyne-sur-mer","tag-lozere","tag-metempirique","tag-milazzo","tag-olla-podrida","tag-paestum","tag-pompei","tag-pors-loubous","tag-prague","tag-puyloubier","tag-saint-petesbourg","tag-sanary-sur-mer","tag-toulon","tag-venise"],"modified_by":"Frank C\u00e9sar LOVISOLO","_links":{"self":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts\/34505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/comments?post=34505"}],"version-history":[{"count":0,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts\/34505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/media\/39874"}],"wp:attachment":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/media?parent=34505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/categories?post=34505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/tags?post=34505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}