{"id":14805,"date":"2015-07-05T19:00:36","date_gmt":"2015-07-05T17:00:36","guid":{"rendered":"https:\/\/frank-lovisolo.fr\/WordPress\/?p=14805"},"modified":"2021-01-14T09:01:06","modified_gmt":"2021-01-14T08:01:06","slug":"nature-morte-3-de-rerum-natura","status":"publish","type":"post","link":"https:\/\/frank-lovisolo.fr\/WordPress\/nature-morte-3-de-rerum-natura\/","title":{"rendered":"Nature Morte III &#8211; De Rerum Natura &#8211; Lucr\u00e8ce"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p><span style=\"color: #ffffff;\">De rerum natura<\/span><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td><a href=\"#com\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"20\" class=\"alignright wp-image-15071 size-full\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/06\/ComBleu.jpg\" alt=\"De rerum natura\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/06\/ComBleu.jpg 250w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/06\/ComBleu-150x12.jpg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">\n<div style=\"text-align: center;\">La mati\u00e8re existe sous forme d&rsquo;atomes imperceptibles<\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: 10px;\">PRINCIPES FONDAMENTAUX DE L&rsquo;ATOMISME <\/span><\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"http:\/\/agoraclass.fltr.ucl.ac.be\/concordances\/lucrece_dnc_I\/lecture\/5.htm\" target=\"_blank\" rel=\"noopener noreferrer\">[Lucr\u00e8ce, De la nature des choses, Livre I]<\/a><\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%;\">\n<div style=\"width: 1024px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-14805-1\" width=\"1024\" height=\"600\" poster=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2014\/07\/Poster5.jpg\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/frank-lovisolo.fr\/soediv\/Nature%20Morte%20III.mp4?_=1\" \/><a href=\"http:\/\/frank-lovisolo.fr\/soediv\/Nature%20Morte%20III.mp4\">http:\/\/frank-lovisolo.fr\/soediv\/Nature%20Morte%20III.mp4<\/a><\/video><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%;\">\n<h4><span style=\"color: #4f4f4f;\"><span style=\"font-size: 24px;\">L<\/span>e film : Nature morte III<\/span><\/h4>\n<div>Recette de tripotage num\u00e9rique:<\/div>\n<div><span style=\"color: #4f4f4f;\">Ingr\u00e9dients : Du sucre <\/span><span style=\"background-color: #000000;\">\u00a0\u00a0<strong><span style=\"color: #ffffff;\">Blanc<\/span><\/strong>\u00a0\u00a0<\/span><span style=\"color: #4f4f4f;\">\u00a0&#8211; Des colorants alimentaires de couleurs primaires\u00a0<\/span><span style=\"background-color: #000000;\">\u00a0\u00a0<strong><span style=\"color: #ff0000;\">Rouge<\/span><\/strong> <span style=\"color: #ffffff;\">&#8211;<\/span> <strong><span style=\"color: #00fff2;\">Cyan<\/span><\/strong>\u00a0<span style=\"color: #ffffff;\">&#8211;<\/span> <strong><span style=\"color: #ffff00;\">Jaune\u00a0<\/span><\/strong>\u00a0<\/span>\u00a0<span style=\"color: #4f4f4f;\">&#8211; De l&rsquo;Encre de Chine <\/span><span style=\"background-color: #d9d9d9;\"><strong><span style=\"color: #000000;\">\u00a0Noir<\/span><\/strong> <\/span><span style=\"color: #4f4f4f;\">\u00a0&#8211; Un liant <\/span><span style=\"background-color: #000000;\">\u00a0<strong><span style=\"color: #d9f2fc;\">H<\/span><\/strong><span style=\"color: #d9f2fc;\"><span style=\"color: #ccffff; font-size: 12px;\">2<\/span><\/span><strong><span style=\"color: #d9f2fc;\">O<\/span><\/strong>\u00a0<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #4f4f4f;\">Sur une serviette blanche arrang\u00e9e, dans une assiette, disposez les morceaux de cette substance extraite de la canne \u00e0 sucre de mani\u00e8re stochastique. De la m\u00eame fa\u00e7on, \u00e9gouttez g\u00e9n\u00e9reusement les encres sur les cubes blancs et ajoutez le liant.\u00a0<\/span><\/div>\n<div><span style=\"color: #4f4f4f;\">Photographiez la dissolution du sucre r\u00e9guli\u00e8rement, en prenant soin de changer d&rsquo;angle et de focale. S\u00e9lectionnez\u00a0les meilleurs clich\u00e9s, montez, musiquez, pr\u00e9sentez en veillant de ne pas omettre le terme num\u00e9rique.<\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--nextpage--><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"vertical-align: middle;\">\n<h4><a href=\"https:\/\/frank-lovisolo.fr\/?p=15156\">La musique du film <\/a>:\u00a0\u00a0De Rerum Natura (sacem 2015).<\/h4>\n<p>\u00a0<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14834\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN.jpg\" alt=\"De rerum natura\" width=\"700\" height=\"225\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN.jpg 2489w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN-560x180.jpg 560w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN-1024x329.jpg 1024w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN-250x80.jpg 250w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/CBDRN-150x48.jpg 150w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>Recette h\u00e9donistique \u00e9gratignant\u00a0la soci\u00e9t\u00e9 J\u00e9suiti\u00e8re de musique.<\/p>\n<div>\u00a0<\/div>\n<div style=\"text-align: justify;\">Prenez un piano de bonne facture et,\u00a0s&rsquo;il s&rsquo;av\u00e8re \u00eatre\u00a0droit, d\u00e9shabillez-le. Pour l&rsquo;autre, \u00e0 queue, contentez-vous de soulever le couvercle !\u00a0<\/div>\n<div style=\"text-align: justify;\">Disposez vos micros et le syst\u00e8me d\u2019enregistrement de mani\u00e8re \u00e9l\u00e9gante.<\/div>\n<div style=\"text-align: justify;\">Faites-vous assister pour la prise de son et le classement des fichiers d&rsquo;une personne qui ne soit point renfrogn\u00e9e: on peut envisager une personne du sexe oppos\u00e9, rien ne l&rsquo;interdit. Il para\u00eetrait que des audacieux l&rsquo;encouragent.<\/div>\n<div style=\"text-align: justify;\">Ensuite, comme bon vous semble, faites subir \u00e0 l&rsquo;instrument des manipulations diverses et des outrages vari\u00e9s afin qu&rsquo;il\u00a0vibre et suscite une p\u00e2leur cacochyme, voire m\u00e9phitique, \u00e0 un premier prix de conservatoire un tantinet \u00e9triqu\u00e9: rien n&rsquo;est plus dr\u00f4le\u00a0!<\/div>\n<div style=\"text-align: justify;\">Dans le feu de l&rsquo;action, vous choisirez quelques objets dans votre cuisine et leur ferez subir, avec malice,\u00a0le\u00a0m\u00eame traitement.<\/div>\n<div style=\"text-align: justify;\">Dans un logiciel d\u2019\u00e9dition audio honn\u00eate et complaisant, vous disposerez les \u00e9chantillons retenus \u00e0 votre incoh\u00e9rente convenance.<\/div>\n<div style=\"text-align: justify;\">Vous les soumettrez \u00e0 d&rsquo;aimables barbaries algorithmiques, le saupoudrerez de quelques cruaut\u00e9s num\u00e9riques et, sans coup f\u00e9rir, vous disposerez ci et l\u00e0 quelques soup\u00e7ons de primitivismes acrimonieux.<\/div>\n<div style=\"text-align: justify;\">Si n\u00e9cessaire, nappez le tout \u00a0de temps lisse \u00e0 l&rsquo;aide d&rsquo;un synth\u00e9tiseur raffin\u00e9 et courtois.<\/div>\n<div style=\"text-align: justify;\">R\u00e9verb\u00e9rez sans fr\u00e9mir, laissez reposer une journ\u00e9e, goutez et ajustez si besoin est.<\/div>\n<p style=\"text-align: justify;\">\u00c0 l&rsquo;aide d\u2019images, sans pr\u00e9venir, servez froidement !<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: justify;\">\n<h3><a href=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Lucretius_De_Rerum_Natura_1675_page_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14837\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Lucretius_De_Rerum_Natura_1675_page_1.jpg\" alt=\"De rerum natura\" width=\"194\" height=\"388\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Lucretius_De_Rerum_Natura_1675_page_1.jpg 480w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Lucretius_De_Rerum_Natura_1675_page_1-75x150.jpg 75w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/a><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lucr%C3%A8ce\" target=\"_blank\" rel=\"noopener noreferrer\">Lucr\u00e8ce<\/a>, De Rerum Natura &#8211; De la nature des choses,<\/h3>\n<h3>Livre I ( Extrait )<\/h3>\n<p><a href=\"http:\/\/agoraclass.fltr.ucl.ac.be\/concordances\/lucrece_dnc_I\/lecture\/5.htm\" target=\"_blank\" rel=\"noopener noreferrer\">I. PRINCIPES FONDAMENTAUX DE L&rsquo;ATOMISME<\/a> (1,146-482)<br \/>\nA. Principe fondamental: Rien ne na\u00eet de rien (1,146-214)<\/p>\n<hr \/>\n<p>\u00a0[1,140 \u00e0 1.210 ] Mais ton m\u00e9rite, cher Memmius, et le plaisir que j&rsquo;attends d&rsquo;une si douce amiti\u00e9, m&rsquo;excitent et m&rsquo;endurcissent au travail, et font que je veille dans le calme des nuits, cherchant des tours heureux et des images po\u00e9tiques qui puissent r\u00e9pandre la clart\u00e9 dans ton \u00e2me, et te d\u00e9couvrir le fond des choses. Or, pour dissiper les terreurs et la nuit des \u00e2mes, c&rsquo;est trop peu des rayons du soleil ou des traits \u00e9blouissants du jour; il faut la raison, et un examen lumineux de la nature. Voici donc le premier axiome qui nous servira de base:Rien ne sort du n\u00e9ant, f\u00fbt-ce m\u00eame sous une main divine.<\/p>\n<p>Ce qui rend les hommes esclaves de la peur, c&rsquo;est que, t\u00e9moins de mille faits accomplis dans le ciel et sur la terre, mais incapables d&rsquo;en apercevoir les causes, ils les imputent \u00e0 une puissance divine. Aussi, d\u00e8s que nous aurons vu que rien ne se fait de rien, d\u00e9j\u00e0 nous distinguerons mieux le but de nos poursuites, et la source d&rsquo;o\u00f9 jaillissent tous les \u00eatres, et la mani\u00e8re dont ils se forment, sans que les dieux y aident.<\/p>\n<p>Si le n\u00e9ant les e\u00fbt enfant\u00e9s, tous les corps\u00a0seraient \u00e0 m\u00eame de produire toutes les esp\u00e8ces, et aucun n&rsquo;aurait besoin de germe. Les hommes na\u00eetraient de l&rsquo;onde, les oiseaux et les poissons de la terre; les troupeaux s&rsquo;\u00e9lanceraient du ciel; et les b\u00eates f\u00e9roces, enfants du hasard, habiteraient sans choix les lieux cultiv\u00e9s ou les d\u00e9serts. Les m\u00eames fruits ne na\u00eetraient pas toujours sur les m\u00eames arbres, mais ils varieraient sans cesse: tous les arbres porteraient tous les fruits. Car si les corps \u00e9taient priv\u00e9s de germes, se pourrait-il qu&rsquo;ils eussent constamment une m\u00eame source?<\/p>\n<p>Mais, au contraire, comme tous les \u00eatres se forment d&rsquo;un \u00e9l\u00e9ment invariable,\u00a0chacun d&rsquo;eux ne vient au monde que l\u00e0 o\u00f9 se trouve sa substance propre, son principe g\u00e9n\u00e9rateur; et ainsi tout ne peut pas na\u00eetre de tout, puisque chaque corps a la vertu de cr\u00e9er un \u00eatre distinct. D&rsquo;ailleurs, pourquoi la rose s&rsquo;ouvre-t-elle au printemps, pourquoi le bl\u00e9 m\u00fbrit-il aux feux de l&rsquo;\u00e9t\u00e9, et la vigne sous la ros\u00e9e de l&rsquo;automne, sinon parce que les germes s&rsquo;amassent \u00e0 temps fixe, et que tout se d\u00e9veloppe dans la bonne saison, et alors que la terre f\u00e9conde ne craint pas d&rsquo;exposer au jour ses productions encore tendres?<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14817 size-medium\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Nature-morte-C-21-560x372.jpg\" alt=\"De rerum natura\" width=\"560\" height=\"372\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Nature-morte-C-21-560x372.jpg 560w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Nature-morte-C-21.jpg 1024w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Nature-morte-C-21-226x150.jpg 226w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/Nature-morte-C-21-150x100.jpg 150w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>Si ces productions \u00e9taient tir\u00e9es du n\u00e9ant, elles na\u00eetraient tout \u00e0 coup, \u00e0 des \u00e9poques incertaines et dans les saisons ennemies, puisqu&rsquo;il n&rsquo;y aurait pas de germes dont le temps contraire p\u00fbt emp\u00eacher les f\u00e9conds assemblages.<\/p>\n<p>D&rsquo;autre part, si le n\u00e9ant engendrait les \u00eatres, une fois leurs \u00e9l\u00e9ments r\u00e9unis, il ne leur faudrait pas un long espace de temps pour cro\u00eetre: les enfants deviendraient aussit\u00f4t des hommes, et l&rsquo;arbuste ne sortirait de terre que pour s&rsquo;\u00e9lancer au ciel.<\/p>\n<p>Et pourtant rien de tout cela n&rsquo;arrive; les \u00eatres grandissent insensiblement (ce qui doit \u00eatre, puisqu&rsquo;ils ont un germe d\u00e9termin\u00e9),\u00a0et en grandissant ils ne changent pas d&rsquo;esp\u00e8ce; ce qui prouve que tous les corps s&rsquo;accroissent et s&rsquo;alimentent de leur substance premi\u00e8re.<\/p>\n<p>J&rsquo;ajoute que, sans les pluies qui l&rsquo;arrosent \u00e0 point fixe, la terre n&rsquo;enfanterait pas ses productions bienfaisantes, et que les animaux, priv\u00e9s de nourriture, ne pourraient multiplier leur esp\u00e8ce ni soutenir leur vie: de sorte qu&rsquo;il vaut mieux admettre l&rsquo;existence de plusieurs \u00e9l\u00e9ments qui se combinent pour former plusieurs \u00eatres, comme nous voyons les lettres produire tous les mots, que celle d&rsquo;un \u00eatre d\u00e9pourvu de germe.<\/p>\n<p>D&rsquo;o\u00f9 vient aussi que la nature\u00a0n&rsquo;a pu b\u00e2tir de ces g\u00e9ants qui traversent les mers \u00e0 pied, qui d\u00e9racinent de vastes montagnes, et dont la vie triomphe de mille g\u00e9n\u00e9rations, si ce n&rsquo;est parce que chaque \u00eatre a une part d\u00e9termin\u00e9e de substance, qui est la mesure de son accroissement?<\/p>\n<p>Il faut donc avouer que rien ne peut se faire de rien, puisque tous les corps ont besoin de semences pour \u00eatre mis au jour et jet\u00e9s dans le souple berceau des airs. Enfin un lieu cultiv\u00e9 a plus de vertu que les terrains incultes, et les fruits s&rsquo;am\u00e9liorent sous des mains actives: la terre renferme donc des principes; et c&rsquo;est en remuant avec la charrue les gl\u00e8bes f\u00e9condes, en bouleversant la surface du sol, que nous les excitons \u00e0 se produire. Car, autrement, toutes choses deviendraient meilleures d&rsquo;elles-m\u00eames, et sans le travail des hommes.<\/p>\n<p>Ajoutons que la nature brise les corps, et les r\u00e9duit \u00e0 leurs simples germes, au lieu de les an\u00e9antir. En effet, si les corps n&rsquo;avaient rien d&rsquo;imp\u00e9rissable, tout ce que nous cesserions de voir cesserait d&rsquo;\u00eatre, et il n&rsquo;y aurait besoin d&rsquo;aucun effort pour entra\u00eener la dissolution des parties et rompre l&rsquo;assemblage. Mais comme tous les \u00eatres, au contraire, sont form\u00e9s d&rsquo;\u00e9l\u00e9ments \u00e9ternels&#8230;<a href=\"http:\/\/agoraclass.fltr.ucl.ac.be\/concordances\/lucrece_dnc_I\/lecture\/default.htm\" target=\"_blank\" rel=\"noopener noreferrer\">La suite &gt;&gt;&gt;&gt;&gt;&gt;&gt;<\/a><\/p>\n<div style=\"text-align: justify;\">\n<hr \/>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: justify;\">\n<p><span style=\"font-size: 16px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14812 size-thumbnail\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/130619_ft98n_pluson_lucrece_sn635-150x150.jpg\" alt=\"De rerum natura\" width=\"150\" height=\"150\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/130619_ft98n_pluson_lucrece_sn635-150x150.jpg 150w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/130619_ft98n_pluson_lucrece_sn635.jpg 357w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\u2022 Lucr\u00e8ce (en latin Titus Lucretius Carus) est un po\u00e8te philosophe latin du ier si\u00e8cle av. J.-C., (peut-\u00eatre 98-55), auteur d&rsquo;un seul livre inachev\u00e9, le De rerum natura (De la nature des choses, qu\u2019on traduit le plus\u00a0souvent par De la nature), un long po\u00e8me passionn\u00e9 qui d\u00e9crit le monde selon les principes d&rsquo;\u00c9picure.<br \/>\nC\u2019est essentiellement gr\u00e2ce \u00e0 lui que nous connaissons l&rsquo;une des plus importantes \u00e9coles philosophiques de l&rsquo;Antiquit\u00e9, l&rsquo;\u00e9picurisme, car des ouvrages d\u2019\u00c9picure, qui fut beaucoup lu et c\u00e9l\u00e9br\u00e9 dans toute l\u2019Antiquit\u00e9 tardive, il ne reste pratiquement rien, sauf trois lettres et quelques sentences.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><br \/>\nSi Lucr\u00e8ce expose fid\u00e8lement la doctrine de son ma\u00eetre, il met \u00e0 la d\u00e9fendre une \u00e2pret\u00e9 nouvelle, une sombre ardeur. \u00ab On entend dans son vers les spectres qui s&rsquo;appellent1. \u00bb dit Hugo. Son temp\u00e9rament angoiss\u00e9 et passionn\u00e9 est presque \u00e0 l\u2019oppos\u00e9 de celui du philosophe grec. Et il vit une \u00e9poque troubl\u00e9e par les guerres civiles et les proscriptions (massacres de Marius, proscriptions de Sylla, r\u00e9volte de Spartacus, conjuration de Catilina). <\/span><\/p>\n<p><span style=\"font-size: 16px;\">De l\u00e0, les pages sombres du De rerum natura sur la mort, le d\u00e9go\u00fbt de la vie, la peste d\u2019Ath\u00e8nes, de l\u00e0 aussi sa passion anti-religieuse qui s\u2019en prend avec acharnement aux dieux, aux cultes et aux pr\u00eatres, passion que l\u2019on ne retrouve pas dans les textes conserv\u00e9s d\u2019\u00c9picure, m\u00eame si celui-ci critique la superstition et m\u00eame la religion populaire. Contre les positions du monde cl\u00e9rical, il propose de se soustraire aux craintes induites par la sph\u00e8re religieuse, \u00e0 laquelle il oppose la dimension rationnelle. Ainsi, il explique de fa\u00e7on mat\u00e9rielle les objets et le vivant, qui prennent forme via des combinaisons d&rsquo;atomes. Surtout Lucr\u00e8ce unit \u00e0 la science \u00e9picurienne, souvent difficile, la douceur et la dimension visionnaire de la po\u00e9sie. <\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span style=\"font-size: 16px;\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lucr%C3%A8ce\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;&gt;&gt;&gt;&gt; \u00a0La suite<\/a><\/span><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 16px;\"><br \/>\n<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14815 size-full\" title=\"De rerum natura\" src=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/AfficheNatureMorteIII.jpg\" alt=\"De rerum natura\" width=\"1024\" height=\"571\" srcset=\"https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/AfficheNatureMorteIII.jpg 1024w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/AfficheNatureMorteIII-560x312.jpg 560w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/AfficheNatureMorteIII-250x139.jpg 250w, https:\/\/frank-lovisolo.fr\/WordPress\/wp-content\/uploads\/2015\/07\/AfficheNatureMorteIII-150x84.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><a id=\"com\"><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-size: 8px; color: #ffffff;\">De rerum natura De rerum natura De rerum natura De rerum natura<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a0406db99f9b\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a0406db99f9b\" checked \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/nature-morte-3-de-rerum-natura\/2\/#la-musique-du-film-de-rerum-natura-sacem-2015\" >La musique du film :\u00a0\u00a0De Rerum Natura (sacem 2015).<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/nature-morte-3-de-rerum-natura\/2\/#lucrece-de-rerum-natura-%e2%80%93-de-la-nature-des-choses\" >Lucr\u00e8ce, De Rerum Natura &#8211; De la nature des choses,<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/nature-morte-3-de-rerum-natura\/2\/#livre-i-extrait\" >Livre I ( Extrait )<\/a><\/li><\/ul><\/nav><\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/frank-lovisolo.fr\/WordPress\/nature-morte-3-de-rerum-natura\/\">Suite &#8211; Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":14815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[514,1,2084],"tags":[1568,1569,1790,1567,734],"class_list":["post-14805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos-compositions","category-tous-les-articles","category-art-libertaire","tag-atomisme","tag-de-la-nature-des-choses","tag-h2o","tag-hedonistique","tag-lucrece"],"_links":{"self":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts\/14805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/comments?post=14805"}],"version-history":[{"count":0,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/posts\/14805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/media\/14815"}],"wp:attachment":[{"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/media?parent=14805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/categories?post=14805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frank-lovisolo.fr\/WordPress\/wp-json\/wp\/v2\/tags?post=14805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}